{"id":5589,"date":"2020-02-19T02:13:01","date_gmt":"2020-02-19T00:13:01","guid":{"rendered":"http:\/\/circular.berlin\/?page_id=5589"},"modified":"2026-02-03T18:14:56","modified_gmt":"2026-02-03T16:14:56","slug":"statutes","status":"publish","type":"page","link":"https:\/\/circular.berlin\/de\/statutes\/","title":{"rendered":"Statuten"},"content":{"rendered":"<h1 style=\"margin-top:var(--wp--preset--spacing--40);margin-bottom:var(--wp--preset--spacing--60)\" class=\"alignwide wp-block-post-title\">Statuten<\/h1>\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-bottom:var(--wp--preset--spacing--60)\">\n<p class=\"wp-block-paragraph\">Diese Satzung wurde am 29.04.2022 aktualisiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e4ambel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Verein verfolgt ausschlie\u00dflich und unmittelbar gemeinn\u00fctzige Zwecke im Sinne des Abschnitts \u201esteuerbeg\u00fcnstigte Zwecke\u201c der Abgabenordnung. Die Zwecke des Vereins unterst\u00fctzen die Entwicklung des Themas \u201eKreislaufwirtschaft\u201c, ein regeneratives System, in dem Ressourceneinsatz und Abfallproduktion, Emissionen und Energieverschwendung durch das Verlangsamen, Verringern und Schlie\u00dfen von Energie- und Materialkreisl\u00e4ufen minimiert werden. Dies kann durch langlebige Konstruktion, Instandhaltung, Reparatur, Wiederverwendung, Remanufacturing, Refurbishing und Recycling erzielt werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 1 Name, Sitz und Gesch\u00e4ftsjahr des Vereins<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Verein f\u00fchrt den Namen \u201eCircular City - Zirkul\u00e4re Stadt e.V.\u201d. Der Verein hat seinen Sitz in Berlin. Der Verein ist beim Amtsgericht Berlin im Vereinsregister eingetragen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 2 Zweck des Vereins<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">(1) F\u00f6rderung des Umweltschutzes und der Umweltbildung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zahlreiche Produkte sind aufgrund ihrer chemischen Zusammensetzung, der Art der Rohstoffgewinnung und Verarbeitung sowohl als umwelt- als auch gesundheitssch\u00e4dlich anzusehen. F\u00fcr Verbraucher, Unternehmen und Verb\u00e4nde sollen daher die Umwelt- und Gesundheitseigenschaften von Produkten, Produktionsweisen und Verwertungsprozessen transparent gemacht werden. Es soll auf die Umstellung auf eine Produktionsweise hingewirkt werden, bei der bereits in der Produktentwicklung das Ziel der Wiedergewinnung und -verwertung von Rohstoffen in technischen und biologischen Kreisl\u00e4ufen, sowie der Verwendung ausschlie\u00dflich nicht-toxischer Inhaltsstoffe verfolgt wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(2) F\u00f6rderung von Verbraucherberatung und Verbraucherschutz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ziel ist die Information und Aufkl\u00e4rung von Verbrauchern \u00fcber Nachhaltigkeitsaspekte, wie soziale und umweltbezogene Faktoren, in den unterschiedlichen Gewerben, die die lokale Kreislaufwirtschaft in den St\u00e4dten beeinflussen k\u00f6nnen. Dadurch soll das Vertrauen von Verbrauchern gest\u00e4rkt und die Bew\u00e4ltigung des \u00dcbergangs zu einer nachhaltigen Wirtschaft, indem langfristige Rentabilit\u00e4t mit sozialer Gerechtigkeit und Umweltschutz verbunden wird, gef\u00f6rdert werden, um dem steigenden Verbraucherinteresse in diesen Belangen nachzukommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 3 T\u00e4tigkeiten und Ma\u00dfnahmen des Vereins<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Satzungszweck wird, entsprechend \u00a7 60 AO, national und international insbesondere durch folgende Ma\u00dfnahmen ausschlie\u00dflich und unmittelbar verwirklicht:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.1. Initiierung, Unterst\u00fctzung und Durchf\u00fchrung von Ma\u00dfnahmen zur Wiedergewinnung der Rohstoffe, wie zum Beispiel der R\u00fcckgabe von gebrauchten Produkten an den Hersteller, als auch innovative umweltgerechte (Produkt-)Ideen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.2. Vertretung der Interessen der Verbraucher an umwelt- und gesundheitsgerechten Produkten und Prozessen in Wirtschaft und Politik.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.3. Bewertung und Empfehlung von Umwelt- und Wirtschaftsprozessen zur Erleichterung von Verbraucherentscheidungen. Diese Dienste werden unentgeltlich zur Verf\u00fcgung gestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.4.     Die Vereinszwecke werden u.a. in Zusammenarbeit mit steuerbeg\u00fcnstigten K\u00f6rperschaften und K\u00f6rperschaften des \u00f6ffentlichen Rechts umgesetzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.5. Die Organisation und Durchf\u00fchrung regelm\u00e4\u00dfiger \u00f6ffentlicher Veranstaltungen zum Austausch zwischen Verbrauchern, Praktikern und Fachexperten und der Vermittlung von Fachwissen an Verbraucher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.6.  Die Organisation und Durchf\u00fchrung regelm\u00e4\u00dfiger Treffen zur B\u00fcndelung und Aufarbeitung von anerkanntem Expertenwissen und bewusstseinsbildender Ma\u00dfnahmen f\u00fcr die Bildung im Thema Kreislaufwirtschaft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00a7 4 Finanzierung<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die erforderlichen Geldmittel werden durch Mitgliedsbeitr\u00e4ge, Akquisition von Spenden, Bu\u00dfgeldern, Erbschaften, anderen privaten und \u00f6ffentlichen Zuwendungen sowie Einnahmen durch Merchandising-Produkte und der Organisation von Veranstaltungen aufgebracht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Methoden zur Akquisition von Geldern sind z.B. Fundraising, Direktmarketing, Crowdfunding, Spendenaufrufe, Sponsorengelder und Einnahmen aus Veranstaltungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Einnahmen aus wirtschaftlichem Gesch\u00e4ftsbetrieb d\u00fcrfen den gesetzlich erlaubten Rahmen, Bestimmungen und aktuelle Gerichtsentscheidungen nicht \u00fcberschreiten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00a7 5 Gemeinn\u00fctzigkeit<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">5.1.     Der Verein verfolgt ausschlie\u00dflich und unmittelbar gemeinn\u00fctzige Zwecke im Sinne des Abschnitts \u201cSteuerbeg\u00fcnstigte Zwecke\u201d der Abgabenordnung (\u00a7\u00a7 56 und 57 AO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.2.     Der Verein ist unabh\u00e4ngig, politisch, parteipolitisch und konfessionell neutral. Er ist selbstlos t\u00e4tig. Sein Zweck ist nicht auf einen wirtschaftlichen Gesch\u00e4ftsbetrieb gerichtet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Demgem\u00e4\u00df d\u00fcrfen Mittel des Vereins nur f\u00fcr satzungsgem\u00e4\u00dfe Zwecke verwendet werden. Die Mitglieder erhalten keine Zuwendungen aus Mitteln der K\u00f6rperschaft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.3 Der Verein darf keine Personen durch Ausgaben, die dem Vereinszweck fremd sind, oder durch unverh\u00e4ltnism\u00e4\u00dfig hohe Verg\u00fctungen beg\u00fcnstigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.4.     Die Mitglieder haben bei ihrem Ausscheiden oder bei der Aufl\u00f6sung oder Aufhebung des Vereins keine Anspr\u00fcche auf sein Verm\u00f6gen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 6 Mitgliedschaft<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.1.      Eintritt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1.1.    Mitglied des Vereins kann jede nat\u00fcrliche Person oder jede juristische Person sein, die sich zum Vereinszweck bekennt. Die Mitgliedschaft ist nicht \u00fcbertragbar und unteilbar. Voraussetzung f\u00fcr den Erwerb der Mitgliedschaft ist ein Aufnahmeantrag in schriftlicher oder digitaler Form, der an den Vorstand zu richten ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1.2. Der Verein hat folgende Arten von Mitgliedern:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ordentliche Mitglieder<\/li>\n\n\n\n<li>F\u00f6rdermitglieder<\/li>\n\n\n\n<li>Aktive ehrenamtliche Mitglieder<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ordentliche Mitglieder<\/strong> haben ein Stimmrecht und leisten einen regelm\u00e4\u00dfigen Mitgliedsbeitrag an den Verein. Ordentliche Mitglieder, insbesondere Vorstandsmitglieder, sind angehalten, die Ziele des Vereins nach M\u00f6glichkeit aktiv zu unterst\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F\u00f6rdermitglieder<\/strong> haben kein Stimmrecht, jedoch die M\u00f6glichkeit, Vorschl\u00e4ge zu Aktivit\u00e4ten des Vereins hervorzubringen und Informationen zu erhalten. F\u00f6rdermitglieder d\u00fcrfen nicht im \u00f6ffentlichen Interesse des Vereins agieren ohne Abstimmung mit den ordentlichen Mitgliedern. F\u00f6rdermitglieder leisten einen regelm\u00e4\u00dfigen Mitgliedsbeitrag an den Verein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aktive ehrenamtliche Mitglieder<\/strong> haben kein Stimmrecht. Aktives ehrenamtliches Mitglied kann werden, wer sich durch aktive Mitarbeit und auf eine gewisse Dauer angelegt in einer der Initiativen des Vereins einbringt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1.3. Der Vorstand entscheidet \u00fcber den Aufnahmeantrag nach freiem Ermessen. Bei Ablehnung des Antrags ist er nicht verpflichtet, dem Antragsteller die Gr\u00fcnde f\u00fcr die Ablehnung mitzuteilen. Die Mitgliederversammlung kann eine Ablehnung mit Mehrheitsbeschluss revidieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1.4.   Die Beitragsh\u00f6he wird vom Vorstand festgesetzt und in einer Beitragsordnung festgelegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1.5.   Die im Mitgliedsantrag erfassten pers\u00f6nlichen Daten werden elektronisch erfasst und k\u00f6nnen gegebenenfalls durch Beauftragte des Vereins, auch f\u00fcr Kontakt-, Informations- und Werbezwecke des Vereins genutzt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.2.     Austritt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.2.1.   Die Mitgliedschaft als Mitglied endet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(a) mit dem Tode des Mitglieds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(b) durch Austrittserkl\u00e4rung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(c) durch Ausschluss aus dem Verein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei juristischen Personen endet die Mitgliedschaft durch ihre Aufl\u00f6sung, ihre Liquidation, die Er\u00f6ffnung des Insolvenzverfahrens \u00fcber ihr Verm\u00f6gen oder durch Abweisung der Er\u00f6ffnung des Insolvenzverfahrens \u00fcber ihr Verm\u00f6gen mangels Masse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.2.2.  Der dem Vorstand gegen\u00fcber schriftlich zu erkl\u00e4rende Austritt ist jederzeit zum Ende des Gesch\u00e4ftsjahres m\u00f6glich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.2.3.  Die F\u00f6rdermitgliedschaft und aktive ehrenamtliche Mitgliedschaft kann jederzeit fristlos gegen\u00fcber dem Verein gek\u00fcndigt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.2.4. Eine R\u00fcckverg\u00fctung von bezahlten Vereinsbeitr\u00e4gen findet nicht statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.3.     Ausschluss<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.3.1.   Ein Mitglied kann aus dem Verein ausgeschlossen werden, wenn es in erheblicher Weise gegen den Vereinszweck verst\u00f6\u00dft, in sonstiger Weise sich grober und wiederholter Verst\u00f6\u00dfe gegen die Vereinssatzung schuldig gemacht hat oder wenn f\u00fcr mindestens zwei Jahre die Beitr\u00e4ge des Mitglieds nicht entrichtet worden sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.3.2.  \u00dcber den Ausschluss entscheidet der Vorstand mit 2\/3 Mehrheit. Dem Mitglied ist vorher Gelegenheit zur \u00c4u\u00dferung zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.3.3.   Die Wiederaufnahme eines ausgeschlossenen Mitgliedes ist fr\u00fchestens nach Ablauf eines Jahres m\u00f6glich. \u00dcber den Antrag entscheidet der Vorstand mit 2\/3 Mehrheit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.4.     Ehrenmitgliedschaft:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.4.1.   Zu Ehrenmitgliedern des Vereins sollen nur solche Personen ernannt werden, die sich um die satzungsgem\u00e4\u00dfen Ziele innerhalb oder au\u00dferhalb des Vereins besonders verdient gemacht haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.4.2. \u00dcber die Ernennung von Ehrenmitgliedern entscheidet der Vorstand. Beitragszahlungen von Ehrenmitgliedern sind freiwillige Leistungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.4.3.  Ehrenmitglieder sind nicht stimmberechtigt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u00a7 7 Organe des Vereins<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Organe des Vereins sind:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.1. die Mitgliederversammlung<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.2. der Vorstand<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.3. der Beirat (geplant)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.4. das Pr\u00e4sidium (geplant)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.5. der Kassenwart<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 8 Die Mitgliederversammlung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">8.1.      Die Mitgliederversammlung ist das oberste Vereinsorgan. Sie ist die h\u00f6chste und letzte Entscheidungs-, Aufsichts- und Beschwerdeinstanz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.2.     Die Mitgliederversammlung findet einmal im Kalenderjahr, in der Regel im ersten Kalenderquartal, statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.3.     Die Einberufung zur Mitgliederversammlung an alle Mitglieder erfolgt schriftlich mindestens vier Wochen vor dem Versammlungstermin durch den Vorstand. Die Tagesordnungspunkte sind in der Einladung bekannt zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferordentliche Mitgliederversammlungen k\u00f6nnen mit einer Frist von 7 Tagen einberufen werden, wenn dies durch Bescheide des Finanzamts f\u00fcr K\u00f6rperschaften oder des Amtsgerichts Charlottenburg kurzfristig notwendig erscheint.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.4.     Jedes ordentliche Mitglied hat das Recht, Antr\u00e4ge und Vorschl\u00e4ge einzubringen, \u00fcber die in der Versammlung beraten und abgestimmt wird. Antr\u00e4ge und Vorschl\u00e4ge der ordentlichen Mitglieder m\u00fcssen dem Vorstand mindestens vier Wochen vor der Versammlung mit entsprechender Begr\u00fcndung bekannt gegeben werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.5.     Versammlungsleiter ist der 1. Vorsitzende des Vorstands, bei dessen Verhinderung sein Stellvertreter, der 2. Vorsitzende.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 9 Beschlussf\u00e4higkeit der Mitgliederversammlung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">9.1.      Die Mitgliederversammlung ist ohne R\u00fccksicht auf die Zahl der erschienenen Mitglieder beschlussf\u00e4hig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.2.      Die Mitgliederversammlung entscheidet bei Beschl\u00fcssen und Wahlen mit einfacher Stimmenmehrheit. Stimmengleichheit bedeutet Ablehnung. Enthaltungen bleiben unber\u00fccksichtigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.3.      \u00dcber Angelegenheiten, die nicht auf der Tagesordnung stehen, ist eine Beschlussfassung nur zul\u00e4ssig, wenn aus der Versammlung kein Widerspruch erhoben wird. Juristische Personen k\u00f6nnen ihr Stimmrecht durch einen Bevollm\u00e4chtigten aus\u00fcben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.4.     Beschl\u00fcsse \u00fcber Satzungs\u00e4nderungen erfordern eine Mehrheit von min. 51% der anwesenden und stimmberechtigten Mitglieder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5.      Beschl\u00fcsse \u00fcber eine \u00c4nderung des Vereinszwecks oder die Aufl\u00f6sung des Vereins setzen einen schriftlichen Antrag von 1\/10 der zu Beginn des Gesch\u00e4ftsjahres festgestellten Mitgliederzahl oder einen vom Vorstand gestellten Antrag voraus. Diese Beschl\u00fcsse bed\u00fcrfen einer Abstimmung in zwei in einem Abstand von fr\u00fchestens 3 und l\u00e4ngstens 6 Monaten aufeinanderfolgenden Mitgliederversammlungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 10 Aufgaben der Mitgliederversammlung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Mitgliederversammlung hat insbesondere folgende Aufgaben zu erf\u00fcllen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entlastung:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.1.     Die Entgegennahme des Berichts des Vorstands und des Kassenwarts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.2.    Die Entgegennahme der Entlastung des Vorstands durch den Kassenwart. Die Vorlage eines unterschriebenen schriftlichen Berichts ist ausreichend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.3.    Die Entlastung des Vorstands durch die Mitglieder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wahlen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.4.    Die Wahl eines Wahlausschusses, bestehend aus einem Wahlleiter und zwei Wahlhelfern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.5.    Die Wahl des 1. und 2. gesch\u00e4ftsf\u00fchrenden Vorstands, der nach Ablauf der Amtszeit f\u00fcr 4 Jahre gew\u00e4hlt wird. Die Wiederwahl ist zul\u00e4ssig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.6.    Die Wahl des erweiterten Vorstands, der nach Ablauf der Amtszeit f\u00fcr 2 Jahre gew\u00e4hlt wird. Die Wiederwahl ist zul\u00e4ssig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.7.    Die Wahl des Schriftf\u00fchrers aus dem Kreis der Mitglieder des erweiterten Vorstands. Die Wiederwahl ist zul\u00e4ssig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.8.    Die Wahl des Kassenwarts. Die Wahl kann per Handzeichen erfolgen. Wiederwahl ist zul\u00e4ssig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.9. Wahlen in der Mitgliederversammlung finden grunds\u00e4tzlich schriftlich und geheim statt, es sei denn, dass die Satzung andere Regelungen vorsieht. Nicht geheime Wahlen m\u00fcssen geheim durchgef\u00fchrt werden, wenn dies von einem der Mitglieder gew\u00fcnscht wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.10.  Vorgeschlagene Kandidaten d\u00fcrfen auch in Abwesenheit gew\u00e4hlt werden. Als gew\u00e4hlt gelten sie erst, wenn sie die Wahl durch eine schriftliche Best\u00e4tigung angenommen haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Satzungs\u00e4nderung, Aufl\u00f6sung, Niederschrift:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.11.   Satzungs\u00e4nderungen k\u00f6nnen nur mit einer Mehrheit von min. 51% der anwesenden und stimmberechtigten Mitglieder beschlossen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.12.  Die Aufl\u00f6sung des Vereins kann nur mit einer Mehrheit von min. 51% der anwesenden und stimmberechtigten Mitglieder beschlossen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.13.  \u00dcber die Mitgliederversammlung ist vom Schriftf\u00fchrer eine Niederschrift zu fertigen, die von ihm und dem Versammlungsleiter zu unterzeichnen ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 11 Der Vorstand<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">11.1.      Der Gesamtvorstand besteht aus dem gesch\u00e4ftsf\u00fchrenden Vorstand, bestehend aus dem 1. Vorsitzenden und seinem Stellvertreter, dem 2. Vorsitzenden, sowie bis zu vier weiteren erweiterten Vorstandsmitgliedern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.2.     Der Vorstand w\u00e4hlt einen Kassenwart.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.3.     Der gesch\u00e4ftsf\u00fchrende Vorstand vertritt den Verein nach innen und au\u00dfen. Der gesch\u00e4ftsf\u00fchrende Vorstand - erster und zweiter Vorsitzender - sind jeweils berechtigt, den Verein einzeln und eigenverantwortlich zu vertreten. Der 1. und 2.  Vorsitzende vertreten den Verein im Sinne des \u00a7 26 BGB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.4.     Der Vorstand bleibt bis zur satzungsgem\u00e4\u00dfen Bestellung des n\u00e4chsten Vorstands im Amt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.5.     Scheidet ein gesch\u00e4ftsf\u00fchrendes Vorstandsmitglied vor Ablauf der Amtsperiode aus, ist vom Gesamtvorstand f\u00fcr den Rest der Amtszeit aus dem Kreis des erweiterten Vorstands kommissarisch ein neues gesch\u00e4ftsf\u00fchrendes Vorstandsmitglied zu w\u00e4hlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.6. Ein Vorstandsmitglied kann nur aus wichtigem Grund (grobe Pflichtverletzung oder Unf\u00e4higkeit zur ordnungsgem\u00e4\u00dfen Gesch\u00e4ftsf\u00fchrung) abberufen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.7.     Der Vorstand hat das Recht, sich eine Gesch\u00e4ftsordnung zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.8.     Der Vorstand hat das Recht, zur Erf\u00fcllung seiner Aufgaben einen Gesch\u00e4ftsf\u00fchrer sowie Mitarbeiter stundenweise oder Vollzeit einzustellen. Diese k\u00f6nnen auch Mitglieder aus dem Kreis des Vorstands sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.9.     Der Vorstand hat das Recht, sich eine Beitragsordnung zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.10.   Der Vorstand hat das Recht, eine bekannte Pers\u00f6nlichkeit aus dem \u00f6ffentlichen Leben die \u00dcbernahme der Schirmherrschaft f\u00fcr den Verein anzutragen. Die Aufgaben des Schirmherrn sind vom Vorstand in Abstimmung mit dem Schirmherrn festzulegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.11.    Der Vorstand hat das Recht, einen Vorstandsbeauftragten zur Erf\u00fcllung gewisser Gesch\u00e4fte und besonderer Aufgaben zu bestellen und einzustellen. Der \u201cBesondere Vertreter\u201d vertritt den Verein im Sinne des \u00a7 30 BGB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.12.    Der Vorstand hat das Recht, zur Erf\u00fcllung umfangreicher Verwaltungsaufgaben, Fundraising und \u00d6ffentlichkeitsarbeit gegen angemessenes Entgelt externe Dienstleister zu beauftragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.13.    Der Kassenwart pr\u00fcft den Jahresbericht und den Abschluss des Vorstands und unterbreitet der Mitgliederversammlung Vorschl\u00e4ge f\u00fcr die Abstimmung \u00fcber die Entlastung des Vorstands.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 12 Beschlussf\u00e4higkeit des Vorstands<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">12.1.     Der Vorstand ist beschlussf\u00e4hig, wenn neben dem 1. Vorsitzenden und dem 2. Vorsitzenden mindestens ein weiteres Mitglied des Vorstands anwesend ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.2.    Der Vorstand entscheidet bei Beschl\u00fcssen und Wahlen mit einfacher Stimmenmehrheit. Bei Stimmengleichheit entscheidet der 1. Vorsitzende oder bei seiner Abwesenheit sein Stellvertreter. Enthaltungen bleiben unber\u00fccksichtigt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 13 Die Gesch\u00e4ftsf\u00fchrung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">13.1.     Die Leitung des Vereins und die laufende F\u00fchrung der Gesch\u00e4fte und der Verwaltung obliegen dem 1. Vorsitzenden des Vorstands und w\u00e4hrend seiner Abwesenheit seinem Stellvertreter, dem 2. Vorsitzenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 14 Der Beirat<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">14.1.     Der Beirat besteht aus dem 1. Vorsitzenden und \/ oder seinem Stellvertreter sowie ordentlichen Mitgliedern, F\u00f6rdermitgliedern und Freunden des Vereins. Beitragszahlungen von Beiratsmitgliedern sind freiwillige Leistungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.2.    Die Mitglieder des Beirats werden vom Vorstand bestellt. Die Mitglieder des Beirats werden f\u00fcr 2 Jahre, l\u00e4ngstens bis zum Ablauf der Wahlperiode des Vorstands bestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.3.    Der Beirat hat die Aufgabe, den Vorstand bei der F\u00fchrung der Gesch\u00e4fte zu beraten, zu unterst\u00fctzen und Vorschl\u00e4ge f\u00fcr den Vorstand zu erarbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.4.    Der Beirat entscheidet mit einfacher Mehrheit der anwesenden Beiratsmitglieder durch Handzeichen. Bei Stimmengleichheit sind Antr\u00e4ge abgelehnt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.5.    \u00dcber jede Beiratssitzung ist eine Niederschrift aufzunehmen und vom Sitzungsleiter zu unterzeichnen. Sitzungsleiter ist in der Regel einer der gesch\u00e4ftsf\u00fchrenden Vorstandsmitglieder.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 15 Das Pr\u00e4sidium<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">15.1.     Das Pr\u00e4sidium besteht aus Personen, die sich bez\u00fcglich der satzungsgem\u00e4\u00dfen Ziele des Vereins besonders verdient gemacht haben. Beitragszahlungen von Pr\u00e4sidiumsmitgliedern sind freiwillige Leistungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15.2.    Die Mitglieder des Pr\u00e4sidiums werden vom Vorstand bestellt. Die Mitglieder des Pr\u00e4sidiums werden f\u00fcr 2 Jahre, l\u00e4ngstens bis zum Ablauf der Wahlperiode des Vorstands bestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15.3.    Das Pr\u00e4sidium hat die Aufgabe, den Vorstand bei der Gestaltung und Umsetzung der \u00d6ffentlichkeitsarbeit und bei der Vermittlung von Kontakten zu beraten, zu unterst\u00fctzen und Vorschl\u00e4ge f\u00fcr den Vorstand zu erarbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15.4.    Das Pr\u00e4sidium entscheidet mit einfacher Mehrheit der anwesenden Pr\u00e4sidiumsmitglieder durch Handzeichen. Bei Stimmengleichheit werden Antr\u00e4ge abgelehnt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15.5.    \u00dcber jede Pr\u00e4sidiumssitzung ist eine Niederschrift aufzunehmen und vom Sitzungsleiter zu unterzeichnen. Sitzungsleiter ist in der Regel einer der gesch\u00e4ftsf\u00fchrenden Vorstandsmitglieder.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 16 Mitgliedsbeitr\u00e4ge<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">16.1.     Jedes ordentliche Mitglied und F\u00f6rdermitglied ist zur Zahlung des Beitrages verpflichtet. Der Vorstand kann in besonderen F\u00e4llen von der Beitragspflicht entbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.2.    Die Beitragsh\u00f6he wird durch eine Beitragsordnung festgelegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.3.    Beitr\u00e4ge sind monatlich oder j\u00e4hrlich zu Beginn des Kalenderjahres bis Ende Februar f\u00fcr das laufende Jahr zu entrichten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.4.    Bei Ausschluss, Austritt oder Tod besteht kein R\u00fcckzahlungsrecht auf geleistete Beitr\u00e4ge.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 17 Der Kassenwart<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">17.1.   Der Kassenwart wird f\u00fcr 2 Jahre gew\u00e4hlt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17.2.   Der Kassenwart darf nicht Mitglied des Vereins sein.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a7 18 Aufl\u00f6sung des Vereins<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">18.1.     Die Aufl\u00f6sung des Vereins kann nur durch die Mitgliederversammlung mit einer Mehrheit von min. 51% der anwesenden und stimmberechtigten Mitglieder beschlossen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.2.    Die Auseinandersetzung erfolgt nach den Vorschriften des BGB. Liquidator ist der gesch\u00e4ftsf\u00fchrende Vorstand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.3.    Bei Aufl\u00f6sung des Vereins oder bei Wegfall steuerbeg\u00fcnstigter Zwecke f\u00e4llt das Vereinsverm\u00f6gen an den Verein \u201eFuture Fashion Forward e.V.\u201c, Leuschnerdamm 13, 10999 Berlin, der es ausschlie\u00dflich und unmittelbar f\u00fcr gemeinn\u00fctzige Zwecke im Sinne des \u00a7 2 zu verwenden hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.4.    Die Aufl\u00f6sung des Vereins ist dem zust\u00e4ndigen Finanzamt unverz\u00fcglich bekannt zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Richtigkeit und Vollst\u00e4ndigkeit der Satzung gem. \u00a771 Abs. 1 S. 4 BGB wird versichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Berlin, den 29.04.2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span lang=\"DE\">Dina Padalkina, (Vorsitzende)<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arianna Nicoletti, <span lang=\"DE\">(stellvertretender Vorsitzender)<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Diese Satzung wurden am 29.04.2022 aktualisiert. Pr\u00e4ambel Der Verein verfolgt ausschlie\u00dflich und unmittelbar gemeinn\u00fctzige Zwecke im Sinne des Abschnitts \u201esteuerbeg\u00fcnstigte Zwecke\u201c der Abgabenordnung. Die Zwecke des Vereins unterst\u00fctzen die Entwicklung des Themas \u201eKreislaufwirtschaft\u201c, ein regeneratives System, in dem Ressourceneinsatz und Abfallproduktion, Emissionen und Energieverschwendung durch das Verlangsamen, Verringern und Schlie\u00dfen von Energie- und Materialkreisl\u00e4ufen minimiert [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"unit":[],"class_list":["post-5589","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Statutes - Circular Berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circular.berlin\/de\/statutes\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statutes - Circular Berlin\" \/>\n<meta property=\"og:description\" content=\"Diese Satzung wurden am 29.04.2022 aktualisiert. Pr\u00e4ambel Der Verein verfolgt ausschlie\u00dflich und unmittelbar gemeinn\u00fctzige Zwecke im Sinne des Abschnitts \u201esteuerbeg\u00fcnstigte Zwecke\u201c der Abgabenordnung. Die Zwecke des Vereins unterst\u00fctzen die Entwicklung des Themas \u201eKreislaufwirtschaft\u201c, ein regeneratives System, in dem Ressourceneinsatz und Abfallproduktion, Emissionen und Energieverschwendung durch das Verlangsamen, Verringern und Schlie\u00dfen von Energie- und Materialkreisl\u00e4ufen minimiert [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circular.berlin\/de\/statutes\/\" \/>\n<meta property=\"og:site_name\" content=\"Circular Berlin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/circularBerlin\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T16:14:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/statutes\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/statutes\\\/\",\"name\":\"Statutes - Circular Berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\"},\"datePublished\":\"2020-02-19T00:13:01+00:00\",\"dateModified\":\"2026-02-03T16:14:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/statutes\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circular.berlin\\\/statutes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/statutes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/circular.berlin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statutes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"name\":\"Circular Berlin\",\"description\":\"Accelerating Berlin\u2019s transition towards a circular city.\",\"publisher\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circular.berlin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\",\"name\":\"Circular Berlin\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"width\":452,\"height\":58,\"caption\":\"Circular Berlin\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/circularBerlin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Satzungen - Rundschreiben Berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circular.berlin\/de\/statutes\/","og_locale":"de_DE","og_type":"article","og_title":"Statutes - Circular Berlin","og_description":"Diese Satzung wurden am 29.04.2022 aktualisiert. Pr\u00e4ambel Der Verein verfolgt ausschlie\u00dflich und unmittelbar gemeinn\u00fctzige Zwecke im Sinne des Abschnitts \u201esteuerbeg\u00fcnstigte Zwecke\u201c der Abgabenordnung. Die Zwecke des Vereins unterst\u00fctzen die Entwicklung des Themas \u201eKreislaufwirtschaft\u201c, ein regeneratives System, in dem Ressourceneinsatz und Abfallproduktion, Emissionen und Energieverschwendung durch das Verlangsamen, Verringern und Schlie\u00dfen von Energie- und Materialkreisl\u00e4ufen minimiert [&hellip;]","og_url":"https:\/\/circular.berlin\/de\/statutes\/","og_site_name":"Circular Berlin","article_publisher":"https:\/\/www.facebook.com\/circularBerlin","article_modified_time":"2026-02-03T16:14:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/circular.berlin\/statutes\/","url":"https:\/\/circular.berlin\/statutes\/","name":"Satzungen - Rundschreiben Berlin","isPartOf":{"@id":"https:\/\/circular.berlin\/#website"},"datePublished":"2020-02-19T00:13:01+00:00","dateModified":"2026-02-03T16:14:56+00:00","breadcrumb":{"@id":"https:\/\/circular.berlin\/statutes\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circular.berlin\/statutes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/circular.berlin\/statutes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circular.berlin\/"},{"@type":"ListItem","position":2,"name":"Statutes"}]},{"@type":"WebSite","@id":"https:\/\/circular.berlin\/#website","url":"https:\/\/circular.berlin\/","name":"Circular Berlin","description":"Beschleunigung des \u00dcbergangs Berlins zu einer kreisf\u00f6rmigen Stadt.","publisher":{"@id":"https:\/\/circular.berlin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circular.berlin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/circular.berlin\/#organization","name":"Circular Berlin","url":"https:\/\/circular.berlin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/","url":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","contentUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","width":452,"height":58,"caption":"Circular Berlin"},"image":{"@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/circularBerlin"]}]}},"_links":{"self":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/pages\/5589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/comments?post=5589"}],"version-history":[{"count":16,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/pages\/5589\/revisions"}],"predecessor-version":[{"id":13157,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/pages\/5589\/revisions\/13157"}],"wp:attachment":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/media?parent=5589"}],"wp:term":[{"taxonomy":"unit","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/unit?post=5589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}