{"id":7306,"date":"2020-08-23T21:16:06","date_gmt":"2020-08-23T19:16:06","guid":{"rendered":"https:\/\/circular.berlin\/?p=7306"},"modified":"2025-12-30T12:53:08","modified_gmt":"2025-12-30T10:53:08","slug":"kreislaufwirtschaft-im-nachhaltigen-wohnungsbau","status":"publish","type":"post","link":"https:\/\/circular.berlin\/de\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/","title":{"rendered":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Im Rahmen des laufenden Projekts \u00fcber Circular Economy in der Bauindustrie, in <a href=\"https:\/\/circular.berlin\/de\/circular-economy-in-berlins-construction-next-level\/\">Zusammenarbeit mit dem EIT Climate-KIC<\/a>, sprach Circular Berlin Circular Berlin mit Stefan Schautes von HOWOGE \u00fcber die Herausforderungen und Chancen der Kreislaufwirtschaft f\u00fcr den nachhaltigen Wohnungsbau.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large is-style-circle-mask\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"638\" src=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE_Stefan_Schautes-620x638-1597311710.jpg\" alt=\"\" class=\"wp-image-7307\" srcset=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE_Stefan_Schautes-620x638-1597311710.jpg 620w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE_Stefan_Schautes-620x638-1597311710-12x12.jpg 12w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE_Stefan_Schautes-620x638-1597311710-292x300.jpg 292w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption><em>Foto: Harry Schnitger<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-text-color has-cyan-bluish-gray-color wp-block-paragraph\"><em>Stefan Schautes ist zust\u00e4ndig f\u00fcr den Bereich Neubau und vertritt die <a href=\"https:\/\/www.howoge.de\">HOWOGE<\/a> als einer der Prokuristen. Seine Aufgaben reichen von der Projektentwicklung \u00fcber die Planrechtschaffung, Planung und Ausf\u00fchrung bis hin zum Ankauf von schl\u00fcsselfertigen Immobilien und Wettbewerbsinitiierungen. <\/em><\/p>\n\n\n\n<p class=\"has-text-color has-cyan-bluish-gray-color wp-block-paragraph\"><em>Es ist eine gek\u00fcrzte Version des Artikels. Das vollst\u00e4ndige Interview wird vom <a href=\"http:\/\/www.recyclingmagazin.de\/2020\/08\/12\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/\">Recycling-Magazin<\/a> ver\u00f6ffentlicht. <\/em><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was bedeutet nachhaltiger Wohnungsbau und wo spielt die Kreislaufwirtschaft eine Rolle?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben das erforscht: Nachhaltigkeit kostet Geld. Wir k\u00f6nnen das aber im sozialen Mietniveau unterbringen - das haben wir nachgewiesen. Solch ein Unterfangen verlangt etwas Innovationswillen und Kraft, Themen auch zu Ende zu denken. Wir wollen als Bestandshalter nachher Wohnungen vermieten, die gesund, nachhaltig und energieoptimiert sind, zu sozialen Mieten von unseren Mietern gerne bewohnt werden und wollen damit trotzdem keine Verluste machen. Das bedeutet, dass wir uns fr\u00fchzeitig mit innovativen Vergabekonzepten besch\u00e4ftigen m\u00fcssen und nicht erst abwarten, bis die Baukosten uns dazu zwingen, etwas zu machen, das wir nicht gelernt haben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich nenne das eine Weitsprungdisziplin. Wir wissen, dass das Thema auf der Agenda steht und dass es irgendwann in Regelwerke m\u00fcndet. Die Howoge ist nicht eine, die abwartet, bis das Regelwerk kommt, sondern wir wollen den Anlauf mitnehmen, dass wir dann auch springen k\u00f6nnen. Wenn man guten Anlauf nimmt, dann nutzen wir die Zeit bis zum Regelwerk f\u00fcr lernen, validieren und erste Erfahrungen machen. Dies immer zusammen mit unseren Partnern und Baufirmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inwieweit ist Kreislaufwirtschaft im nachhaltigen Wohnungsbau realisierbar? Was sind aktuelle Anwendungen und Einschr\u00e4nkungen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recyclingbeton kann man an vielen Stellen verwenden, wir k\u00f6nnen Holz einsetzen, wir k\u00f6nnen l\u00f6sungsmittelfreie Oberbel\u00e4ge verlegen, wir k\u00f6nnen monolithisch planen und bauen und wir k\u00f6nnen Schichtmaterialien weglassen, was die beste L\u00f6sung f\u00fcr den Cradle-to-cradle-Ansatz ist. Au\u00dferdem w\u00fcrde ich sagen, dass Vermeidung eine Strategie ist, die wir auf alle F\u00e4lle \u00f6fter bedienen sollten. Das hei\u00dft: architektonisch und st\u00e4dteplanerisch so clever vorzugehen, dass L\u00f6sungen keinen sinnlosen Mehraufwand erzeugen und gleichzeitig eine hohe Qualit\u00e4t erf\u00fcllen sowie ein gewisses Level an Behaglichkeit und Komfort.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"384\" src=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Urbaner-Holzbau_Klaus-Dombrowsky-681x384-1.jpg\" alt=\"\" class=\"wp-image-7308\" srcset=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Urbaner-Holzbau_Klaus-Dombrowsky-681x384-1.jpg 681w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Urbaner-Holzbau_Klaus-Dombrowsky-681x384-1-18x10.jpg 18w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Urbaner-Holzbau_Klaus-Dombrowsky-681x384-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><figcaption><em>Projekt Urbaner Holzbau<\/em><br><em>Foto: Klaus Dombrowsky<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-left wp-block-paragraph\">Wir haben zum Beispiel das Thema Holz f\u00fcr uns entdeckt. In Adlershof haben wir mit den Holzcubes ein kleines Projekt mit 42 Wohnungen realisiert, wo Holz auch tr\u00e4gt. Das werden wir uns aktuell nicht leisten k\u00f6nnen, denn Holz tragend auszubilden ist kostenm\u00e4\u00dfig noch ziemlich aufwendig. <br><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Man kann Holz millimetergenau zuschneiden, der Rohbau hat aber nach DIN drei Zentimeter Toleranzgr\u00f6\u00dfe und das zu organisieren kostet Geld. Wenn man dann komplett in Holz baut, wird das vermeintlich leichter, da entwickelt sich die Holzindustrie auch gerade hin. Dazu m\u00fcssen und wollen wir die Nachfrage nach Holz noch verst\u00e4rken, dann sollte die Bauindustrie Holz auch mehr f\u00fcr sich, uns und den sozialen Wohnungsbau entdecken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie k\u00f6nnen die n\u00e4chsten Schritte und L\u00f6sungen f\u00fcr die Kreislaufwirtschaft 2.0 im nachhaltigen Wohnungsbau aussehen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gemischte Nutzung<\/strong>: Die Howoge setzt sich f\u00fcr das Durchmischen der Stadt ein, um tags\u00fcber wieder Gewerbe und Arbeitspl\u00e4tze in monostrukturierten Wohngebieten zu haben, damit deren Tagesabw\u00e4rme \u00fcber einen W\u00e4rmetauscher abends die Wohnungen beheizen kann. Es geht beispielsweise um das Zusammenbringen unterschiedlicher Nutzungen in Nachbarschaften, um Leitungsverluste zu minimieren, sodass die Abh\u00e4ngigkeiten von Nachbarschaften \u00fcber einen physikalischen Prozess steuerbar sind. Es geht aber auch darum, kurze Wege zwischen Wohnen und Arbeiten zu erzielen, um Mobilit\u00e4t effizienter zu gestalten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Experten-Netzwerk: <\/strong>Die Kernakteure sind in Berlin noch ziemlich unsortiert. Wir w\u00fcrden es begr\u00fc\u00dfen, wenn es einen Thinktank g\u00e4be, der das Thema Kreislaufwirtschaft in der Bauindustrie nicht nur theoretisch aufgreift, sondern Vielen und Vielenm einen Mehrwert gibt, wenn wir gemeinsam in die Anwendung kommen. Es geht nur gemeinsam, der Gesetzgeber kann M\u00f6glichkeiten und Fokussierung schaffen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kreislaufwirtschaft als Triebfeder: <\/strong>Ich w\u00fcnsche mir au\u00dferdem, dass wir die M\u00f6glichkeit oder die Chance erkennen, dass durch zirkul\u00e4res Bauen auch eine wirtschaftliche Triebfeder entsteht. Jeder sollte anfangen, in Architekturb\u00fcros die Mitarbeiter auf <a href=\"https:\/\/www.c2ccertified.org\/get-certified\/product-certification\">von der Wiege bis zur Wiege<\/a> zu schulen. Die Bauindustrie sollte sich auf den Weg machen andere Bezugsquellen zu identifizieren als das seit zehn Jahren gute Betonwerk, wenn es sich nicht mit Recyclingbeton besch\u00e4ftigt. Da w\u00fcnsche ich mir eine Offenheit und eine Erkenntnis, dass das auch wirtschaftliche Vorteile haben wird oder, dass einfach ein Angebot entsteht, auf das es eine Nachfrage generiert. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zusammenarbeit<\/strong>: Abschlie\u00dfend sollten wir gemeinsame Ziele definieren und begreifen, dass das nur kooperativ funktioniert. <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/app.recyclingmagazin.de\/en\/profiles\/a00082d39ef5\/editions\/a68f688ce2243fe0a247\/pages\/page\/10\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"246\" src=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-1024x246.jpg\" alt=\"\" class=\"wp-image-6488\" srcset=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-1024x246.jpg 1024w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-18x4.jpg 18w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-300x72.jpg 300w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-768x185.jpg 768w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-1536x369.jpg 1536w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/RM-magazine-neu-blau-1-2048x492.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">Lesen Sie die vollst\u00e4ndige Version des Interviews im <a href=\"https:\/\/www.recyclingmagazin.de\/2020\/08\/12\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/\">Recycling Magazin<\/a>. <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/dach.climate-kic.org\/en\/what-we-offer\/ecosystems\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/copy-solid1-1.png\" alt=\"\" class=\"wp-image-6487\" width=\"70\" height=\"80\" srcset=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/copy-solid1-1.png 140w, https:\/\/circular.berlin\/wp-content\/uploads\/2020\/05\/copy-solid1-1-11x12.png 11w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">Erfahren Sie mehr \u00fcber <a href=\"https:\/\/dach.climate-kic.org\/en\/what-we-offer\/ecosystems\/\">Kreislaufwirtschaft in der Bauindustrie in Deutschland <\/a>und lesen Sie den vollst\u00e4ndigen Bericht <a href=\"https:\/\/dach.climate-kic.org\/wp-content\/uploads\/sites\/20\/2020\/02\/1912_Circular-Construction-in-Berlin_Circular-Berlin.pdf\">\u201cBerlins zirkul\u00e4res Bau\u00f6kosystem\u201d<\/a>. <\/p>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Kontakt<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Marina Petrova, Kommunikation und zirkul\u00e4re gebaute Umwelt <a>marina@circular.berlin<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Im Rahmen des laufenden Projekts \u00fcber Circular Economy in der Bauindustrie, in Zusammenarbeit mit dem EIT Climate-KIC, sprach Circular Berlin Circular Berlin mit Stefan Schautes von HOWOGE \u00fcber die He\u00adrausforderungen und Chancen der Kreislaufwirtschaft f\u00fcr den nachhaltigen Wohnungsbau. Stefan Schautes ist zust\u00e4ndig f\u00fcr den Bereich Neubau und vertritt die HOWOGE als einer der Prokuristen. Seine [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":7311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[256],"tags":[214,133,197],"unit":[],"topic":[],"class_list":["post-7306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-circular-construction","tag-circular-materials","tag-interview"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin<\/title>\n<meta name=\"description\" content=\"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circular.berlin\/de\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin\" \/>\n<meta property=\"og:description\" content=\"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circular.berlin\/de\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/\" \/>\n<meta property=\"og:site_name\" content=\"Circular Berlin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/circularBerlin\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-23T19:16:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T10:53:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CB team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"CB team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/\"},\"author\":{\"name\":\"CB team\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/person\\\/52c7e81b23d86a0391760d9989951257\"},\"headline\":\"Kreislaufwirtschaft im nachhaltigen Wohnungsbau\",\"datePublished\":\"2020-08-23T19:16:06+00:00\",\"dateModified\":\"2025-12-30T10:53:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/\"},\"wordCount\":835,\"publisher\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg\",\"keywords\":[\"circular construction\",\"circular materials\",\"interview\"],\"articleSection\":[\"Article\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/\",\"name\":\"Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg\",\"datePublished\":\"2020-08-23T19:16:06+00:00\",\"dateModified\":\"2025-12-30T10:53:08+00:00\",\"description\":\"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg\",\"contentUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg\",\"width\":1000,\"height\":710,\"caption\":\"Neubau-Quartier an der \\u2028Stra\u00dfe-Am-Flugplatz, \\u2028Berlin-Johannisthal Visualisierung: roedig.schop.architekten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/circular.berlin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kreislaufwirtschaft im nachhaltigen Wohnungsbau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"name\":\"Circular Berlin\",\"description\":\"Accelerating Berlin\u2019s transition towards a circular city.\",\"publisher\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circular.berlin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\",\"name\":\"Circular Berlin\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"width\":452,\"height\":58,\"caption\":\"Circular Berlin\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/circularBerlin\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/person\\\/52c7e81b23d86a0391760d9989951257\",\"name\":\"CB team\",\"url\":\"https:\\\/\\\/circular.berlin\\\/de\\\/author\\\/guest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin","description":"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circular.berlin\/de\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/","og_locale":"de_DE","og_type":"article","og_title":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin","og_description":"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.","og_url":"https:\/\/circular.berlin\/de\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/","og_site_name":"Circular Berlin","article_publisher":"https:\/\/www.facebook.com\/circularBerlin","article_published_time":"2020-08-23T19:16:06+00:00","article_modified_time":"2025-12-30T10:53:08+00:00","og_image":[{"width":1000,"height":710,"url":"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg","type":"image\/jpeg"}],"author":"CB team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"CB team","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#article","isPartOf":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/"},"author":{"name":"CB team","@id":"https:\/\/circular.berlin\/#\/schema\/person\/52c7e81b23d86a0391760d9989951257"},"headline":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau","datePublished":"2020-08-23T19:16:06+00:00","dateModified":"2025-12-30T10:53:08+00:00","mainEntityOfPage":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/"},"wordCount":835,"publisher":{"@id":"https:\/\/circular.berlin\/#organization"},"image":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#primaryimage"},"thumbnailUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg","keywords":["circular construction","circular materials","interview"],"articleSection":["Article"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/","url":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/","name":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau - Circular Berlin","isPartOf":{"@id":"https:\/\/circular.berlin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#primaryimage"},"image":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#primaryimage"},"thumbnailUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg","datePublished":"2020-08-23T19:16:06+00:00","dateModified":"2025-12-30T10:53:08+00:00","description":"Architecture, engineering, and construction industry faces an unprecedented urgent need to be at the forefront of systematic change towards circular economy. Accelerating the transition to a circular built environment, together with EIT Climate-KIC, Dina Padalkina, one of the founders of Circular Berlin, spoke to Andrea Klinge to obtain key insights on the circular economy in the construction sector in Berlin and beyond.","breadcrumb":{"@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#primaryimage","url":"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg","contentUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2020\/08\/HOWOGE-Stra\u00dfe-Am-Flugplatz_RoedigSchopArchitekten-scaled-1-e1598192205188.jpg","width":1000,"height":710,"caption":"Neubau-Quartier an der \u2028Stra\u00dfe-Am-Flugplatz, \u2028Berlin-Johannisthal Visualisierung: roedig.schop.architekten"},{"@type":"BreadcrumbList","@id":"https:\/\/circular.berlin\/article\/kreislaufwirtschaft-im-nachhaltigen-wohnungsbau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circular.berlin\/"},{"@type":"ListItem","position":2,"name":"Kreislaufwirtschaft im nachhaltigen Wohnungsbau"}]},{"@type":"WebSite","@id":"https:\/\/circular.berlin\/#website","url":"https:\/\/circular.berlin\/","name":"Circular Berlin","description":"Beschleunigung des \u00dcbergangs Berlins zu einer kreisf\u00f6rmigen Stadt.","publisher":{"@id":"https:\/\/circular.berlin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circular.berlin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/circular.berlin\/#organization","name":"Circular Berlin","url":"https:\/\/circular.berlin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/","url":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","contentUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","width":452,"height":58,"caption":"Circular Berlin"},"image":{"@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/circularBerlin"]},{"@type":"Person","@id":"https:\/\/circular.berlin\/#\/schema\/person\/52c7e81b23d86a0391760d9989951257","name":"CB-Team","url":"https:\/\/circular.berlin\/de\/author\/guest\/"}]}},"_links":{"self":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/7306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/comments?post=7306"}],"version-history":[{"count":5,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/7306\/revisions"}],"predecessor-version":[{"id":7315,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/7306\/revisions\/7315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/media\/7311"}],"wp:attachment":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/media?parent=7306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/categories?post=7306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/tags?post=7306"},{"taxonomy":"unit","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/unit?post=7306"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/topic?post=7306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}