{"id":9058,"date":"2022-04-26T17:39:09","date_gmt":"2022-04-26T15:39:09","guid":{"rendered":"https:\/\/circular.berlin\/?p=9058"},"modified":"2025-12-30T12:46:03","modified_gmt":"2025-12-30T10:46:03","slug":"neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen","status":"publish","type":"post","link":"https:\/\/circular.berlin\/de\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/","title":{"rendered":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen."},"content":{"rendered":"\n<p>Die Europ\u00e4ische Kommission ver\u00f6ffentlichte Anfang 2020 einen \u201eNeuen Aktionsplan f\u00fcr die Kreislaufwirtschaft\u201c, ein zentraler Baustein des European Green Deal. Mit Ma\u00dfnahmen und Regelungen die sich \u00fcber den gesamten Lebenszyklus von Produkten erstrecken \u2013 vom Design \u00fcber die Herstellung bis zum Verbrauch \u2013 soll der \u00dcbergang zu einer Kreislaufwirtschaft beschleunigt werden. Eine nachhaltigere Produktpolitik soll gew\u00e4hrleisten, \u201edass [&#8230;] Produkte so konzipiert sind, dass sie \u00fcber eine l\u00e4ngere Lebensdauer verf\u00fcgen, leichter wiederverwendet, repariert und recycelt werden k\u00f6nnen und einen gr\u00f6\u00dftm\u00f6glichen Anteil recycelter Materialien statt Prim\u00e4rrohstoffe enthalten.\u201c (<a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/de\/ip_20_420\">Quelle<\/a>). Dabei konzentrieren sich die Ma\u00dfnahmen auf Sektoren mit besonders gro\u00dfem Ressourcenverbrauch wie Textilien, Bauwesen und Geb\u00e4ude, Elektronik sowie Lebensmittel.<\/p>\n\n\n\n<p>Am 30. M\u00e4rz dieses Jahres legte die EU-Kommission dazu ein Ma\u00dfnahmenpaket nach. Kernst\u00fcck ist der im Rahmen der Initiative f\u00fcr nachhaltige Produkte ausgearbeitete Vorschlag zur Einf\u00fchrung einer neuen \u00d6kodesign-Verordnung. Geplant ist einerseits die Erweiterung der bislang geltenden \u00d6kodesign-Richtlinie um Anforderungen, die nicht nur die Energieeffizienz, sondern auch die Kreislauff\u00e4higkeit und die Verringerung der Umwelt- und Klimaauswirkungen f\u00f6rdern. Andererseits soll die Richtlinie auf nahezu alle in der EU angebotenen G\u00fcter ausgeweitet werden. So k\u00f6nnten in Zukunft auch f\u00fcr Textilien, M\u00f6bel und Bauprodukte bestimmte \u00f6kologische Mindeststandarts hinsichtlich ihrer Lebensdauer, Reparierbarkeit und Recyclingf\u00e4higkeit gelten. Gleichzeitig sollen alle unter die Verordnung fallenden Produkte mit digitalen Produktp\u00e4ssen versehen werden, die Informationen \u00fcber die materielle Zusammensetzung und Beschaffenheit enthalten. Dies f\u00fchrt zu mehr Transparenz entlang der Lieferkette und soll das Reparieren und Recycling von G\u00fctern erleichtern.<\/p>\n\n\n\n<p>Neben neuen \u00d6kodesign-Anforderungen und der Einf\u00fchrung von digitalen Produktp\u00e4ssen sollen u.a. verbindliche EU-Regelungen f\u00fcr eine erweiterte Herstellerverantwortung dazu beitragen, die Lebensdauer von Textilien zu verl\u00e4ngern und somit gegen \u201eFast-Fashion\u201c anzugehen. Entsprechend sollen Unternehmen Verantwortung f\u00fcr die Nachnutzungsphase, d.h. f\u00fcr eine fachgerechte Sammlung, Sortierung und Entsorgung bzw. das Recycling ihrer Produkte \u00fcbernehmen. Auch beinhaltet das Paket Vorschl\u00e4ge zur St\u00e4rkung der Position von Verbrauchern und Verbraucherinnen. Damit fundierte Kaufentscheidungen getroffen werden k\u00f6nnen, soll der Zugang zu umweltrelevanten Produktinformationen erleichtert werden. Zudem will die Kommission \u201eGreenwashing\u201c verbieten. Vage Produktangaben wie \u201egr\u00fcn\u201c und \u201eumweltfreundlich\u201c bed\u00fcrfen zuk\u00fcnftig Nachweispflichten, sollten sich die Vorschl\u00e4ge durchsetzen (<a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/de\/ip_22_2013\">Quelle<\/a>).<\/p>\n\n\n\n<p>Dar\u00fcber hinaus hat sich die EU-Kommission dazu verpflichtet noch dieses Jahr einen Gesetzesvorschlag zum \u201eRecht auf Reparatur\u201c vorzulegen (<a href=\"https:\/\/www.europarl.europa.eu\/news\/de\/press-room\/20220401IPR26537\/recht-auf-reparatur-fur-produkte-die-langlebiger-und-reparierbar-sind\">Quelle<\/a>). VerbraucherInnen sollen die M\u00f6glichkeit haben, ihre Produkte selbst zu reparieren oder sie von Drittanbietern reparieren zu lassen. Daf\u00fcr m\u00fcssen Produkte so gestaltet werden, dass ihre Einzelteile leicht zug\u00e4nglich und ausbaubar sind. VerbaucherInnen und Reparaturbetriebe sollen kostenlosen Zugang zu den erforderlichen Reparatur- und Wartungsinformationen erhalten. Das EU-Parlament hat hierzu bereits einen Entschlie\u00dfungsentwurf eingebracht, um die bevorstehende Gesetzgebung zu beeinflussen.Umweltverb\u00e4nde begr\u00fc\u00dfen das Paket. \u201eDie EU-Kommission will den Weg f\u00fcr weitere Nachhaltigkeitsanforderungen an Produkte freimachen. Das ist ein richtiger Schritt\u201c, so die BUND-Gesch\u00e4ftsf\u00fchrerin Antje von Broock. Allerdings \u201egilt es zu zeigen, dass die neue EU-Initiative nicht nur zur Ressourceneffizienz beisteuert, sondern auch unseren Ressourcenhunger insgesamt verringert. Diesbez\u00fcgliche Ziele auf EU- oder nationaler Ebene fehlen jedoch noch\u201c (<a href=\"https:\/\/www.bund.net\/service\/presse\/pressemitteilungen\/detail\/news\/kommentar-eu-initiative-zu-nachhaltigen-produkten-muss-ressourcenverbrauch-massgeblich-verringern\/\">quelle<\/a>), f\u00fchrt von Broock weiter aus. \u00c4hnliche Kritik kommt vom European Environmental Bureau: \u201cThe package is a fundamental step forward but still lacks teeth to make sustainable products the norm.\u201d (<a href=\"https:\/\/eeb.org\/new-circular-economy-package-set-to-be-a-game-changer\/\">Quelle<\/a>) M\u00f6glichkeiten, schnelle Ergebnisse zu erzielen, wie etwa das Verbot unverkaufte Waren zu vernichten, seien nicht genutzt worden. Stattdessen seien wir aufgrund langer Verhandlungsprozesse noch weit davon entfernt, die Ma\u00dfnahmen in die Praxis umzusetzen. Schlie\u00dflich mangele es noch an verbindlichen Zielvorgaben und Konkretisierungen, die den Erfolg des Aktionsplans entscheidend mitbestimmen werden.<\/p>\n\n\n\n<figure class=\"wp-block-image size-vp_sm is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/TDA1X110X-U034745JX4N-c3ec702acb2a-512-500x500.png\" alt=\"\" class=\"wp-image-9060\" width=\"75\" height=\"75\"\/><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><em>Der Artikel ist von\u00a0<strong>\u00a0<\/strong>Mischa Jorkowski<\/em> <em>vorbereitet.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Europ\u00e4ische Kommission ver\u00f6ffentlichte Anfang 2020 einen \u201eNeuen Aktionsplan f\u00fcr die Kreislaufwirtschaft\u201c, ein zentraler Baustein des European Green Deal. Mit Ma\u00dfnahmen und Regelungen die sich \u00fcber den gesamten Lebenszyklus von Produkten erstrecken \u2013 vom Design \u00fcber die Herstellung bis zum Verbrauch \u2013 soll der \u00dcbergang zu einer Kreislaufwirtschaft beschleunigt werden. Eine nachhaltigere Produktpolitik soll gew\u00e4hrleisten, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[256],"tags":[251],"unit":[],"topic":[],"class_list":["post-9058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-regulation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circular.berlin\/de\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin\" \/>\n<meta property=\"og:description\" content=\"Die Europ\u00e4ische Kommission ver\u00f6ffentlichte Anfang 2020 einen \u201eNeuen Aktionsplan f\u00fcr die Kreislaufwirtschaft\u201c, ein zentraler Baustein des European Green Deal. Mit Ma\u00dfnahmen und Regelungen die sich \u00fcber den gesamten Lebenszyklus von Produkten erstrecken \u2013 vom Design \u00fcber die Herstellung bis zum Verbrauch \u2013 soll der \u00dcbergang zu einer Kreislaufwirtschaft beschleunigt werden. Eine nachhaltigere Produktpolitik soll gew\u00e4hrleisten, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circular.berlin\/de\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"Circular Berlin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/circularBerlin\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T15:39:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T10:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dina Padalkina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dina Padalkina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/\"},\"author\":{\"name\":\"Dina Padalkina\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/person\\\/4862ab2317155471f7bb0ebaeaeb4440\"},\"headline\":\"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft &#8211; EU will nachhaltige Produkte zur Norm machen.\",\"datePublished\":\"2022-04-26T15:39:09+00:00\",\"dateModified\":\"2025-12-30T10:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/\"},\"wordCount\":624,\"publisher\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\",\"keywords\":[\"Regulation\"],\"articleSection\":[\"Article\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/\",\"name\":\"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\",\"datePublished\":\"2022-04-26T15:39:09+00:00\",\"dateModified\":\"2025-12-30T10:46:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\",\"contentUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/article\\\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/circular.berlin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft &#8211; EU will nachhaltige Produkte zur Norm machen.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#website\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"name\":\"Circular Berlin\",\"description\":\"Accelerating Berlin\u2019s transition towards a circular city.\",\"publisher\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circular.berlin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#organization\",\"name\":\"Circular Berlin\",\"url\":\"https:\\\/\\\/circular.berlin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/circular.berlin\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CB_Logo.svg\",\"width\":452,\"height\":58,\"caption\":\"Circular Berlin\"},\"image\":{\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/circularBerlin\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/circular.berlin\\\/#\\\/schema\\\/person\\\/4862ab2317155471f7bb0ebaeaeb4440\",\"name\":\"Dina Padalkina\",\"url\":\"https:\\\/\\\/circular.berlin\\\/de\\\/author\\\/dpadalkina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circular.berlin\/de\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin","og_description":"Die Europ\u00e4ische Kommission ver\u00f6ffentlichte Anfang 2020 einen \u201eNeuen Aktionsplan f\u00fcr die Kreislaufwirtschaft\u201c, ein zentraler Baustein des European Green Deal. Mit Ma\u00dfnahmen und Regelungen die sich \u00fcber den gesamten Lebenszyklus von Produkten erstrecken \u2013 vom Design \u00fcber die Herstellung bis zum Verbrauch \u2013 soll der \u00dcbergang zu einer Kreislaufwirtschaft beschleunigt werden. Eine nachhaltigere Produktpolitik soll gew\u00e4hrleisten, [&hellip;]","og_url":"https:\/\/circular.berlin\/de\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/","og_site_name":"Circular Berlin","article_publisher":"https:\/\/www.facebook.com\/circularBerlin","article_published_time":"2022-04-26T15:39:09+00:00","article_modified_time":"2025-12-30T10:46:03+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","type":"image\/jpeg"}],"author":"Dina Padalkina","twitter_card":"summary_large_image","twitter_image":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","twitter_misc":{"Verfasst von":"Dina Padalkina","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#article","isPartOf":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/"},"author":{"name":"Dina Padalkina","@id":"https:\/\/circular.berlin\/#\/schema\/person\/4862ab2317155471f7bb0ebaeaeb4440"},"headline":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft &#8211; EU will nachhaltige Produkte zur Norm machen.","datePublished":"2022-04-26T15:39:09+00:00","dateModified":"2025-12-30T10:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/"},"wordCount":624,"publisher":{"@id":"https:\/\/circular.berlin\/#organization"},"image":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","keywords":["Regulation"],"articleSection":["Article"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/","url":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/","name":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft - EU will nachhaltige Produkte zur Norm machen. - Circular Berlin","isPartOf":{"@id":"https:\/\/circular.berlin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#primaryimage"},"image":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","datePublished":"2022-04-26T15:39:09+00:00","dateModified":"2025-12-30T10:46:03+00:00","breadcrumb":{"@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#primaryimage","url":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","contentUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2022\/04\/guillaume-perigois-0NRkVddA2fw-unsplash-scaled-e1650987184338.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/circular.berlin\/article\/neue-vorschlage-fur-die-kreislaufwirtschaft-eu-will-nachhaltige-produkte-zur-norm-machen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circular.berlin\/"},{"@type":"ListItem","position":2,"name":"Neue Vorschl\u00e4ge f\u00fcr die Kreislaufwirtschaft &#8211; EU will nachhaltige Produkte zur Norm machen."}]},{"@type":"WebSite","@id":"https:\/\/circular.berlin\/#website","url":"https:\/\/circular.berlin\/","name":"Rundschreiben Berlin","description":"Beschleunigung des \u00dcbergangs Berlins zu einer kreisf\u00f6rmigen Stadt.","publisher":{"@id":"https:\/\/circular.berlin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circular.berlin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/circular.berlin\/#organization","name":"Rundschreiben Berlin","url":"https:\/\/circular.berlin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/","url":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","contentUrl":"https:\/\/circular.berlin\/wp-content\/uploads\/2026\/02\/CB_Logo.svg","width":452,"height":58,"caption":"Circular Berlin"},"image":{"@id":"https:\/\/circular.berlin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/circularBerlin"]},{"@type":"Person","@id":"https:\/\/circular.berlin\/#\/schema\/person\/4862ab2317155471f7bb0ebaeaeb4440","name":"Dina Padalkina","url":"https:\/\/circular.berlin\/de\/author\/dpadalkina\/"}]}},"_links":{"self":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/9058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/comments?post=9058"}],"version-history":[{"count":1,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/9058\/revisions"}],"predecessor-version":[{"id":9061,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/posts\/9058\/revisions\/9061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/media\/9059"}],"wp:attachment":[{"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/media?parent=9058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/categories?post=9058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/tags?post=9058"},{"taxonomy":"unit","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/unit?post=9058"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/circular.berlin\/de\/wp-json\/wp\/v2\/topic?post=9058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}